{"id":652,"count":21,"description":"Oil paintings with landscape theme.","link":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/","name":"Landscape","slug":"landscape","taxonomy":"category","parent":447,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landscape Archivos - Jacco Van Den Hoek<\/title>\n<meta name=\"description\" content=\"Oil paintings with landscape theme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landscape Archivos - Jacco Van Den Hoek\" \/>\n<meta property=\"og:description\" content=\"Oil paintings with landscape theme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacco Van Den Hoek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/oil-paintings\\\/landscape\\\/\",\"url\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/oil-paintings\\\/landscape\\\/\",\"name\":\"Landscape Archivos - Jacco Van Den Hoek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/#website\"},\"description\":\"Oil paintings with landscape theme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/oil-paintings\\\/landscape\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/oil-paintings\\\/landscape\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Art\",\"item\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oil paintings\",\"item\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/category\\\/art\\\/oil-paintings\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Landscape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/\",\"name\":\"Jacco Van Den Hoek\",\"description\":\"Jacco Van Den Hoek\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jaccovandenhoek.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landscape Archivos - Jacco Van Den Hoek","description":"Oil paintings with landscape theme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/","og_locale":"en_US","og_type":"article","og_title":"Landscape Archivos - Jacco Van Den Hoek","og_description":"Oil paintings with landscape theme.","og_url":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/","og_site_name":"Jacco Van Den Hoek","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/","url":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/","name":"Landscape Archivos - Jacco Van Den Hoek","isPartOf":{"@id":"https:\/\/jaccovandenhoek.com\/en\/#website"},"description":"Oil paintings with landscape theme.","breadcrumb":{"@id":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/landscape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Art","item":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/"},{"@type":"ListItem","position":2,"name":"Oil paintings","item":"https:\/\/jaccovandenhoek.com\/en\/category\/art\/oil-paintings\/"},{"@type":"ListItem","position":3,"name":"Landscape"}]},{"@type":"WebSite","@id":"https:\/\/jaccovandenhoek.com\/en\/#website","url":"https:\/\/jaccovandenhoek.com\/en\/","name":"Jacco Van Den Hoek","description":"Jacco Van Den Hoek","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jaccovandenhoek.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/jaccovandenhoek.com\/en\/wp-json\/wp\/v2\/categories\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaccovandenhoek.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/jaccovandenhoek.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/jaccovandenhoek.com\/en\/wp-json\/wp\/v2\/categories\/447"}],"wp:post_type":[{"href":"https:\/\/jaccovandenhoek.com\/en\/wp-json\/wp\/v2\/posts?categories=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}